{"id":730,"date":"2006-09-17T01:42:56","date_gmt":"2006-09-16T21:42:56","guid":{"rendered":"http:\/\/www.ukrupnenie.com\/countries\/c\/costa-rica\/costa-rica-legislative-election-2006.html"},"modified":"2007-09-17T01:43:38","modified_gmt":"2007-09-16T21:43:38","slug":"costa-rica-legislative-election-2006","status":"publish","type":"post","link":"https:\/\/www.electoralgeography.com\/new\/en\/countries\/c\/costa-rica\/costa-rica-legislative-election-2006.html","title":{"rendered":"Costa Rica. Legislative Election 2006"},"content":{"rendered":"<p><\/p>\n<table class=\"rowstyle-alt\" id=\"wptable\" >\n\t<thead>\n\t<tr>\n\t\t<th class=\"sortable-numeric\" style=\"width:30px\" align=\"left\">Regions<\/th>\n\t\t<th class=\"sortable-numeric\" style=\"width:30px\" align=\"center\">Citizens Action Party<\/th>\n\t\t<th class=\"sortable-numeric\" style=\"width:30px\" align=\"center\">Social Christian Unity Party<\/th>\n\t\t<th class=\"sortable-numeric\" style=\"width:30px\" align=\"center\">National Liberation Part<\/th>\n\t\t<th class=\"sortable-numeric\" style=\"width:30px\" align=\"center\">Libertarian Movement Party<\/th>\n\t<\/tr>\n\t<\/thead>\n\t<tr>\n\t\t<td style=\"width:30px\" align=\"left\">Total<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">25.34%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">7.82%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">36.54%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">9.17%<\/td>\n\t<\/tr>\n\t<tr class=\"alt\">\n\t\t<td style=\"width:30px\" align=\"left\">SAN JOSE<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">26.12%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">6.21%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">33.57%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">9.20%<\/td>\n\t<\/tr>\n\t<tr>\n\t\t<td style=\"width:30px\" align=\"left\">ALAJUELA<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">27.74%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">6.92%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">37.27%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">7.81%<\/td>\n\t<\/tr>\n\t<tr class=\"alt\">\n\t\t<td style=\"width:30px\" align=\"left\">CARTAGO<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">27.67%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">7.10%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">35.16%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">10.41%<\/td>\n\t<\/tr>\n\t<tr>\n\t\t<td style=\"width:30px\" align=\"left\">HEREDIA<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">30.64%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">8.27%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">36.36%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">9.00%<\/td>\n\t<\/tr>\n\t<tr class=\"alt\">\n\t\t<td style=\"width:30px\" align=\"left\">GUANACASTE<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">16.58%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">10.88%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">44.70%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">7.24%<\/td>\n\t<\/tr>\n\t<tr>\n\t\t<td style=\"width:30px\" align=\"left\">PUNTARENAS<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">18.60%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">12.27%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">44.73%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">10.02%<\/td>\n\t<\/tr>\n\t<tr class=\"alt\">\n\t\t<td style=\"width:30px\" align=\"left\">LIMON<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">17.41%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">12.32%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">36.95%<\/td>\n\t\t<td style=\"width:30px\" align=\"center\">11.72%<\/td>\n\t<\/tr>\n<\/table><p>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Regions Citizens Action Party Social Christian Unity Party National Liberation Part Libertarian Movement Party Total 25.34% 7.82% 36.54% 9.17% SAN JOSE 26.12% 6.21% 33.57% 9.20% ALAJUELA 27.74% 6.92% 37.27% 7.81% CARTAGO 27.67% 7.10% 35.16% 10.41% HEREDIA 30.64% 8.27% 36.36% 9.00% GUANACASTE 16.58% 10.88% 44.70% 7.24% PUNTARENAS 18.60% 12.27% 44.73% 10.02% LIMON 17.41% 12.32% 36.95% 11.72%<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[62],"tags":[],"_links":{"self":[{"href":"https:\/\/www.electoralgeography.com\/new\/en\/wp-json\/wp\/v2\/posts\/730"}],"collection":[{"href":"https:\/\/www.electoralgeography.com\/new\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.electoralgeography.com\/new\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.electoralgeography.com\/new\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.electoralgeography.com\/new\/en\/wp-json\/wp\/v2\/comments?post=730"}],"version-history":[{"count":0,"href":"https:\/\/www.electoralgeography.com\/new\/en\/wp-json\/wp\/v2\/posts\/730\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.electoralgeography.com\/new\/en\/wp-json\/wp\/v2\/media?parent=730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.electoralgeography.com\/new\/en\/wp-json\/wp\/v2\/categories?post=730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.electoralgeography.com\/new\/en\/wp-json\/wp\/v2\/tags?post=730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}